{"id":10489,"date":"2025-07-07T16:04:21","date_gmt":"2025-07-07T15:04:21","guid":{"rendered":"https:\/\/edebex.com\/blog\/retrasos-en-los-pagos-en-espana-el-verano-puede-convertirse-en-una-pesadilla-para-las-pymes\/"},"modified":"2025-07-07T16:06:05","modified_gmt":"2025-07-07T15:06:05","slug":"retrasos-en-los-pagos-en-espana-el-verano-puede-convertirse-en-una-pesadilla-para-las-pymes","status":"publish","type":"post","link":"https:\/\/edebex.com\/es\/blog\/retrasos-en-los-pagos-en-espana-el-verano-puede-convertirse-en-una-pesadilla-para-las-pymes\/","title":{"rendered":"Retrasos en los pagos en Espa\u00f1a: el verano puede convertirse en una pesadilla para las pymes"},"content":{"rendered":"<h3><strong>Con la llegada del verano, muchos empresarios no solo sufren por el calor. Tambi\u00e9n lo hacen al ver c\u00f3mo los plazos de pago se alargan y los impagos se acumulan. La raz\u00f3n es bien conocida: las vacaciones. Es una situaci\u00f3n recurrente y, aunque previsible, puede tener consecuencias graves para las peque\u00f1as y medianas empresas.<\/strong><\/h3>\n<p>El verano sugiere descanso y desconexi\u00f3n, pero para muchos directivos es justo lo contrario. Seg\u00fan datos de <a href=\"https:\/\/www.informa.es\/en\">INFORMA D&amp;B<\/a>, durante este periodo aumentan los retrasos en los pagos, superando en ocasiones los 15 d\u00edas. La causa suele ser la misma: la ausencia del personal clave \u2014como contables o directores financieros\u2014 ralentiza la validaci\u00f3n y el abono de facturas. Esta situaci\u00f3n afecta a empresas de todos los tama\u00f1os, pero su impacto es especialmente severo en las m\u00e1s peque\u00f1as.<\/p>\n<h3><strong>La tesorer\u00eda se tensiona<\/strong><\/h3>\n<p>El problema es claro: tienes facturas pendientes de cobro que suponen una parte importante de tus ingresos, pero debes seguir pagando a proveedores y cumplir con tus compromisos. Es decir, necesitas liquidez\u2026 que sigue retenida en manos de tus clientes.<\/p>\n<p>No es algo exclusivo del verano, pero s\u00ed se agrava. Cuando el responsable financiero de tu cliente se va de vacaciones durante varias semanas, todo se ralentiza. Y aunque el problema est\u00e1 en su lado, la presi\u00f3n recae sobre ti. Como una cuerda demasiado tensa, tu tesorer\u00eda corre el riesgo de romperse antes de que llegue septiembre.<\/p>\n<p>Y no solo eso: los retrasos generan m\u00e1s trabajo. Reclamaciones, recordatorios, seguimientos\u2026 Una carga administrativa que te aleja de lo que realmente importa: hacer crecer tu negocio.<\/p>\n<h3><strong>De un simple retraso a una reacci\u00f3n en cadena<\/strong><\/h3>\n<p>En este contexto, el riesgo de un efecto domin\u00f3 es real. Un cliente que no paga a tiempo puede comprometer tu tesorer\u00eda, lo que a su vez puede hacer que t\u00fa tambi\u00e9n retrases tus pagos. As\u00ed, la tensi\u00f3n se transmite a lo largo de toda la cadena de suministro.<\/p>\n<p>Y como suele suceder, las m\u00e1s afectadas son las pymes, que cuentan con menos margen para absorber estos desequilibrios.<\/p>\n<h3><strong>Antic\u00edpate: protege tu negocio antes del golpe<\/strong><\/h3>\n<p>Mientras algunos desconectan, t\u00fa puedes tomar medidas para evitar que esta situaci\u00f3n temporal se convierta en una crisis prolongada:<\/p>\n<ul>\n<li>Eval\u00faa bien a tus clientes antes de cerrar acuerdos. Establece condiciones claras y espec\u00edficas sobre plazos de pago y penalizaciones por incumplimiento.<\/li>\n<li>Emite facturas sin errores, utiliza facturaci\u00f3n electr\u00f3nica y redacta condiciones generales que te protejan de verdad.<\/li>\n<li>Antic\u00edpate al periodo vacacional hablando con tus clientes. Pacta cobros antes de las ausencias, incluso ofreciendo alg\u00fan incentivo a cambio.<\/li>\n<li>Establece un proceso claro, firme y constante de gesti\u00f3n de cobros. No improvises.<\/li>\n<li>Y, como dice el refr\u00e1n: \u00abNo esperes a tener sed para buscar el pozo\u00bb. Antic\u00edpate al bache de liquidez y prep\u00e1rate con soluciones de financiaci\u00f3n alternativas. En <a href=\"https:\/\/edebex.com\/es\/\">Edebex,<\/a> te ayudamos a transformar tus facturas en liquidez en cuesti\u00f3n de d\u00edas. No esperes a que el problema crezca. Vende tus facturas y protege tu tesorer\u00eda este verano.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Con la llegada del verano, muchos empresarios no solo sufren por el calor. Tambi\u00e9n lo hacen al ver c\u00f3mo los plazos de pago se alargan y los impagos se acumulan. La raz\u00f3n es bien conocida: las vacaciones. Es una situaci\u00f3n recurrente y, aunque previsible, puede tener consecuencias graves para las peque\u00f1as y medianas empresas. El [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":8029,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[503],"tags":[],"class_list":["post-10489","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Retrasos en los pagos en Espa\u00f1a: el verano puede convertirse en una pesadilla para las pymes | Edebex<\/title>\n<meta name=\"description\" content=\"Con la llegada del verano, muchos empresarios no solo sufren por el calor. Tambi\u00e9n lo hacen al ver c\u00f3mo los plazos de pago se alargan y los impagos se acumulan.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/edebex.com\/es\/blog\/retrasos-en-los-pagos-en-espana-el-verano-puede-convertirse-en-una-pesadilla-para-las-pymes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Retrasos en los pagos en Espa\u00f1a: el verano puede convertirse en una pesadilla para las pymes\" \/>\n<meta property=\"og:description\" content=\"Con la llegada del verano, muchos empresarios no solo sufren por el calor. Tambi\u00e9n lo hacen al ver c\u00f3mo los plazos de pago se alargan y los impagos se acumulan.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/edebex.com\/es\/blog\/retrasos-en-los-pagos-en-espana-el-verano-puede-convertirse-en-una-pesadilla-para-las-pymes\/\" \/>\n<meta property=\"og:site_name\" content=\"edebex\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Edebex\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-07T15:04:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-07T15:06:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/edebex.com\/wp-content\/uploads\/2017\/12\/action-daylight-diver1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"marketing intern 2\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@edebex\" \/>\n<meta name=\"twitter:site\" content=\"@edebex\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"marketing intern 2\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/edebex.com\\\/es\\\/blog\\\/retrasos-en-los-pagos-en-espana-el-verano-puede-convertirse-en-una-pesadilla-para-las-pymes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/edebex.com\\\/es\\\/blog\\\/retrasos-en-los-pagos-en-espana-el-verano-puede-convertirse-en-una-pesadilla-para-las-pymes\\\/\"},\"author\":{\"name\":\"marketing intern 2\",\"@id\":\"https:\\\/\\\/edebex.com\\\/es\\\/#\\\/schema\\\/person\\\/2e6c66bcddfee6fad192582a126dd021\"},\"headline\":\"Retrasos en los pagos en Espa\u00f1a: el verano puede convertirse en una pesadilla para las pymes\",\"datePublished\":\"2025-07-07T15:04:21+00:00\",\"dateModified\":\"2025-07-07T15:06:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/edebex.com\\\/es\\\/blog\\\/retrasos-en-los-pagos-en-espana-el-verano-puede-convertirse-en-una-pesadilla-para-las-pymes\\\/\"},\"wordCount\":545,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/edebex.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/edebex.com\\\/es\\\/blog\\\/retrasos-en-los-pagos-en-espana-el-verano-puede-convertirse-en-una-pesadilla-para-las-pymes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/edebex.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/action-daylight-diver1.jpg\",\"articleSection\":[\"Sin categorizar\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/edebex.com\\\/es\\\/blog\\\/retrasos-en-los-pagos-en-espana-el-verano-puede-convertirse-en-una-pesadilla-para-las-pymes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/edebex.com\\\/es\\\/blog\\\/retrasos-en-los-pagos-en-espana-el-verano-puede-convertirse-en-una-pesadilla-para-las-pymes\\\/\",\"url\":\"https:\\\/\\\/edebex.com\\\/es\\\/blog\\\/retrasos-en-los-pagos-en-espana-el-verano-puede-convertirse-en-una-pesadilla-para-las-pymes\\\/\",\"name\":\"Retrasos en los pagos en Espa\u00f1a: el verano puede convertirse en una pesadilla para las pymes | Edebex\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/edebex.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/edebex.com\\\/es\\\/blog\\\/retrasos-en-los-pagos-en-espana-el-verano-puede-convertirse-en-una-pesadilla-para-las-pymes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/edebex.com\\\/es\\\/blog\\\/retrasos-en-los-pagos-en-espana-el-verano-puede-convertirse-en-una-pesadilla-para-las-pymes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/edebex.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/action-daylight-diver1.jpg\",\"datePublished\":\"2025-07-07T15:04:21+00:00\",\"dateModified\":\"2025-07-07T15:06:05+00:00\",\"description\":\"Con la llegada del verano, muchos empresarios no solo sufren por el calor. Tambi\u00e9n lo hacen al ver c\u00f3mo los plazos de pago se alargan y los impagos se acumulan.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/edebex.com\\\/es\\\/blog\\\/retrasos-en-los-pagos-en-espana-el-verano-puede-convertirse-en-una-pesadilla-para-las-pymes\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/edebex.com\\\/es\\\/blog\\\/retrasos-en-los-pagos-en-espana-el-verano-puede-convertirse-en-una-pesadilla-para-las-pymes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/edebex.com\\\/es\\\/blog\\\/retrasos-en-los-pagos-en-espana-el-verano-puede-convertirse-en-una-pesadilla-para-las-pymes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/edebex.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/action-daylight-diver1.jpg\",\"contentUrl\":\"https:\\\/\\\/edebex.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/action-daylight-diver1.jpg\",\"width\":1200,\"height\":1800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/edebex.com\\\/es\\\/blog\\\/retrasos-en-los-pagos-en-espana-el-verano-puede-convertirse-en-una-pesadilla-para-las-pymes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/edebex.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retrasos en los pagos en Espa\u00f1a: el verano puede convertirse en una pesadilla para las pymes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/edebex.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/edebex.com\\\/es\\\/\",\"name\":\"edebex - The digital alternative to factoring\",\"description\":\"beta\",\"publisher\":{\"@id\":\"https:\\\/\\\/edebex.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/edebex.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/edebex.com\\\/es\\\/#organization\",\"name\":\"Edebex\",\"url\":\"https:\\\/\\\/edebex.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/edebex.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/edebex.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/logo-edebex.png\",\"contentUrl\":\"https:\\\/\\\/edebex.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/logo-edebex.png\",\"width\":464,\"height\":216,\"caption\":\"Edebex\"},\"image\":{\"@id\":\"https:\\\/\\\/edebex.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Edebex\",\"https:\\\/\\\/x.com\\\/edebex\",\"https:\\\/\\\/www.instagram.com\\\/edebex_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/edebex\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7KdkFY6t-CJvz5l6tTFAlw\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/edebex.com\\\/es\\\/#\\\/schema\\\/person\\\/2e6c66bcddfee6fad192582a126dd021\",\"name\":\"marketing intern 2\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ac478fcdbb2c06218c09daa92158a75ad2e51ff29f99cf22643fc781fe7c62c8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ac478fcdbb2c06218c09daa92158a75ad2e51ff29f99cf22643fc781fe7c62c8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ac478fcdbb2c06218c09daa92158a75ad2e51ff29f99cf22643fc781fe7c62c8?s=96&d=mm&r=g\",\"caption\":\"marketing intern 2\"},\"url\":\"https:\\\/\\\/edebex.com\\\/es\\\/blog\\\/author\\\/marketing-intern-2\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Retrasos en los pagos en Espa\u00f1a: el verano puede convertirse en una pesadilla para las pymes | Edebex","description":"Con la llegada del verano, muchos empresarios no solo sufren por el calor. Tambi\u00e9n lo hacen al ver c\u00f3mo los plazos de pago se alargan y los impagos se acumulan.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/edebex.com\/es\/blog\/retrasos-en-los-pagos-en-espana-el-verano-puede-convertirse-en-una-pesadilla-para-las-pymes\/","og_locale":"es_ES","og_type":"article","og_title":"Retrasos en los pagos en Espa\u00f1a: el verano puede convertirse en una pesadilla para las pymes","og_description":"Con la llegada del verano, muchos empresarios no solo sufren por el calor. Tambi\u00e9n lo hacen al ver c\u00f3mo los plazos de pago se alargan y los impagos se acumulan.","og_url":"https:\/\/edebex.com\/es\/blog\/retrasos-en-los-pagos-en-espana-el-verano-puede-convertirse-en-una-pesadilla-para-las-pymes\/","og_site_name":"edebex","article_publisher":"https:\/\/www.facebook.com\/Edebex","article_published_time":"2025-07-07T15:04:21+00:00","article_modified_time":"2025-07-07T15:06:05+00:00","og_image":[{"width":1200,"height":1800,"url":"https:\/\/edebex.com\/wp-content\/uploads\/2017\/12\/action-daylight-diver1.jpg","type":"image\/jpeg"}],"author":"marketing intern 2","twitter_card":"summary_large_image","twitter_creator":"@edebex","twitter_site":"@edebex","twitter_misc":{"Escrito por":"marketing intern 2","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/edebex.com\/es\/blog\/retrasos-en-los-pagos-en-espana-el-verano-puede-convertirse-en-una-pesadilla-para-las-pymes\/#article","isPartOf":{"@id":"https:\/\/edebex.com\/es\/blog\/retrasos-en-los-pagos-en-espana-el-verano-puede-convertirse-en-una-pesadilla-para-las-pymes\/"},"author":{"name":"marketing intern 2","@id":"https:\/\/edebex.com\/es\/#\/schema\/person\/2e6c66bcddfee6fad192582a126dd021"},"headline":"Retrasos en los pagos en Espa\u00f1a: el verano puede convertirse en una pesadilla para las pymes","datePublished":"2025-07-07T15:04:21+00:00","dateModified":"2025-07-07T15:06:05+00:00","mainEntityOfPage":{"@id":"https:\/\/edebex.com\/es\/blog\/retrasos-en-los-pagos-en-espana-el-verano-puede-convertirse-en-una-pesadilla-para-las-pymes\/"},"wordCount":545,"commentCount":0,"publisher":{"@id":"https:\/\/edebex.com\/es\/#organization"},"image":{"@id":"https:\/\/edebex.com\/es\/blog\/retrasos-en-los-pagos-en-espana-el-verano-puede-convertirse-en-una-pesadilla-para-las-pymes\/#primaryimage"},"thumbnailUrl":"https:\/\/edebex.com\/wp-content\/uploads\/2017\/12\/action-daylight-diver1.jpg","articleSection":["Sin categorizar"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/edebex.com\/es\/blog\/retrasos-en-los-pagos-en-espana-el-verano-puede-convertirse-en-una-pesadilla-para-las-pymes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/edebex.com\/es\/blog\/retrasos-en-los-pagos-en-espana-el-verano-puede-convertirse-en-una-pesadilla-para-las-pymes\/","url":"https:\/\/edebex.com\/es\/blog\/retrasos-en-los-pagos-en-espana-el-verano-puede-convertirse-en-una-pesadilla-para-las-pymes\/","name":"Retrasos en los pagos en Espa\u00f1a: el verano puede convertirse en una pesadilla para las pymes | Edebex","isPartOf":{"@id":"https:\/\/edebex.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/edebex.com\/es\/blog\/retrasos-en-los-pagos-en-espana-el-verano-puede-convertirse-en-una-pesadilla-para-las-pymes\/#primaryimage"},"image":{"@id":"https:\/\/edebex.com\/es\/blog\/retrasos-en-los-pagos-en-espana-el-verano-puede-convertirse-en-una-pesadilla-para-las-pymes\/#primaryimage"},"thumbnailUrl":"https:\/\/edebex.com\/wp-content\/uploads\/2017\/12\/action-daylight-diver1.jpg","datePublished":"2025-07-07T15:04:21+00:00","dateModified":"2025-07-07T15:06:05+00:00","description":"Con la llegada del verano, muchos empresarios no solo sufren por el calor. Tambi\u00e9n lo hacen al ver c\u00f3mo los plazos de pago se alargan y los impagos se acumulan.","breadcrumb":{"@id":"https:\/\/edebex.com\/es\/blog\/retrasos-en-los-pagos-en-espana-el-verano-puede-convertirse-en-una-pesadilla-para-las-pymes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/edebex.com\/es\/blog\/retrasos-en-los-pagos-en-espana-el-verano-puede-convertirse-en-una-pesadilla-para-las-pymes\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/edebex.com\/es\/blog\/retrasos-en-los-pagos-en-espana-el-verano-puede-convertirse-en-una-pesadilla-para-las-pymes\/#primaryimage","url":"https:\/\/edebex.com\/wp-content\/uploads\/2017\/12\/action-daylight-diver1.jpg","contentUrl":"https:\/\/edebex.com\/wp-content\/uploads\/2017\/12\/action-daylight-diver1.jpg","width":1200,"height":1800},{"@type":"BreadcrumbList","@id":"https:\/\/edebex.com\/es\/blog\/retrasos-en-los-pagos-en-espana-el-verano-puede-convertirse-en-una-pesadilla-para-las-pymes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/edebex.com\/es\/"},{"@type":"ListItem","position":2,"name":"Retrasos en los pagos en Espa\u00f1a: el verano puede convertirse en una pesadilla para las pymes"}]},{"@type":"WebSite","@id":"https:\/\/edebex.com\/es\/#website","url":"https:\/\/edebex.com\/es\/","name":"edebex - The digital alternative to factoring","description":"beta","publisher":{"@id":"https:\/\/edebex.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/edebex.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/edebex.com\/es\/#organization","name":"Edebex","url":"https:\/\/edebex.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/edebex.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/edebex.com\/wp-content\/uploads\/2019\/12\/logo-edebex.png","contentUrl":"https:\/\/edebex.com\/wp-content\/uploads\/2019\/12\/logo-edebex.png","width":464,"height":216,"caption":"Edebex"},"image":{"@id":"https:\/\/edebex.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Edebex","https:\/\/x.com\/edebex","https:\/\/www.instagram.com\/edebex_off\/","https:\/\/www.linkedin.com\/company\/edebex\/","https:\/\/www.youtube.com\/channel\/UC7KdkFY6t-CJvz5l6tTFAlw"]},{"@type":"Person","@id":"https:\/\/edebex.com\/es\/#\/schema\/person\/2e6c66bcddfee6fad192582a126dd021","name":"marketing intern 2","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ac478fcdbb2c06218c09daa92158a75ad2e51ff29f99cf22643fc781fe7c62c8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ac478fcdbb2c06218c09daa92158a75ad2e51ff29f99cf22643fc781fe7c62c8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ac478fcdbb2c06218c09daa92158a75ad2e51ff29f99cf22643fc781fe7c62c8?s=96&d=mm&r=g","caption":"marketing intern 2"},"url":"https:\/\/edebex.com\/es\/blog\/author\/marketing-intern-2\/"}]}},"_links":{"self":[{"href":"https:\/\/edebex.com\/es\/wp-json\/wp\/v2\/posts\/10489","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/edebex.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/edebex.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/edebex.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/edebex.com\/es\/wp-json\/wp\/v2\/comments?post=10489"}],"version-history":[{"count":1,"href":"https:\/\/edebex.com\/es\/wp-json\/wp\/v2\/posts\/10489\/revisions"}],"predecessor-version":[{"id":10490,"href":"https:\/\/edebex.com\/es\/wp-json\/wp\/v2\/posts\/10489\/revisions\/10490"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/edebex.com\/es\/wp-json\/wp\/v2\/media\/8029"}],"wp:attachment":[{"href":"https:\/\/edebex.com\/es\/wp-json\/wp\/v2\/media?parent=10489"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/edebex.com\/es\/wp-json\/wp\/v2\/categories?post=10489"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/edebex.com\/es\/wp-json\/wp\/v2\/tags?post=10489"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}