{"id":3806,"date":"2020-04-16T15:50:18","date_gmt":"2020-04-16T15:50:18","guid":{"rendered":"https:\/\/edebex.com\/?p=3806"},"modified":"2021-02-11T15:07:46","modified_gmt":"2021-02-11T14:07:46","slug":"coronavirus-comment-sauver-votre-tresorerie","status":"publish","type":"post","link":"https:\/\/edebex.com\/fr\/blog\/coronavirus-comment-sauver-votre-tresorerie\/","title":{"rendered":"Coronavirus: comment \u00ab\u00a0sauver\u00a0\u00bb votre tr\u00e9sorerie?"},"content":{"rendered":"<p><strong>La plan\u00e8te est l\u2019arr\u00eat. Cette crise sanitaire sans pr\u00e9c\u00e9dent r\u00e9cent fragilise l\u2019ensemble de l\u2019\u00e9difice \u00e9conomique, \u00e0 commencer par les PME. L\u2019heure est grave et il faut agir vite\u2026 et bien! Premiers pas? Sautez sur les mesures d\u2019urgence mises en place par le Gouvernement. <\/strong><\/p>\n<p>Que votre activit\u00e9 soit paralys\u00e9e, en demi-teinte ou qu\u2019elle tourne au contraire \u00e0 pleins gaz, vous sentirez passer les effets de la crise. M\u00eame si vous tirez (encore) votre \u00e9pingle du jeu, vos clients pourraient conna\u00eetre d\u2019importantes difficult\u00e9s: baisses du chiffre d\u2019affaires et retards de paiements en cascade se profilent \u00e0 l\u2019horizon. Sans rentr\u00e9es d\u2019argent, vous subirez la situation (au moins) par ricochet. Ces difficult\u00e9s pr\u00e9visibles ont amen\u00e9 le Gouvernement et les acteurs financiers \u00e0 prendre des mesures uniques\u2026 Le but? Aider les PME \u00e0 garder la t\u00eate \u2014 et leur tr\u00e9sorerie \u2014 hors de l\u2019eau.<\/p>\n<h3><strong>Sollicitez l\u2019aide disponible<\/strong><\/h3>\n<p>Pour freiner une chute, il faut s\u2019accrocher aux branches, faire preuve de sang-froid puis de cr\u00e9ativit\u00e9 pour rebondir. Vous n\u2019\u00eates pas seul, alors pas de d\u00e9faitisme ni de politique de l\u2019autruche. Premier r\u00e9flexe? Saisissez tous les leviers mis \u00e0 votre disposition pour prot\u00e9ger votre tr\u00e9sorerie: des d\u00e9lais de paiement suppl\u00e9mentaires \u00e0 l\u2019acc\u00e8s \u00ab\u00a0facilit\u00e9\u00a0\u00bb aux sources de financement, tout est bon \u00e0 prendre. Une fois ces m\u00e9canismes activ\u00e9s, n\u2019attendez pas que les secours arrivent: cherchez vos propres solutions pour limiter les d\u00e9g\u00e2ts.<\/p>\n<h3><strong>Vos obligations sociales et fiscales? Reportez, reportez, reportez!<\/strong><\/h3>\n<ol>\n<li><strong>La course aux d\u00e9lais de paiement <\/strong><\/li>\n<\/ol>\n<p>Compte tenu des probl\u00e8mes de tr\u00e9sorerie pr\u00e9sents et futurs, prenez contact avec les diff\u00e9rents organismes pour demander de repousser vos \u00e9ch\u00e9ances fiscales et sociales:<\/p>\n<ul>\n<li><strong>Imp\u00f4ts directs<\/strong>: votre service des imp\u00f4ts des entreprises (SIE) est \u00e0 votre \u00e9coute pour retarder le paiement de vos \u00e9ch\u00e9ances, entre autres, vos acomptes d\u2019imp\u00f4t sur les soci\u00e9t\u00e9s et les taxes sur les salaires. Ne vous en privez pas, car aucune p\u00e9nalit\u00e9 ne sera appliqu\u00e9e;<\/li>\n<li><strong>Cotisations sociales<\/strong>: m\u00eame topo pour vos cotisations sociales (salariales et patronales) aupr\u00e8s de l\u2019URSSAF. Vous pouvez obtenir jusqu\u2019\u00e0 3\u00a0mois de moratoire sans frais additionnels;<\/li>\n<\/ul>\n<p>Vous \u00eates ind\u00e9pendant? C\u2019est pareil \u00e0 quelques d\u00e9tails pr\u00e8s.<\/p>\n<ul>\n<li><strong>Pour vos \u00e9ch\u00e9ances fiscales<\/strong>, ajustez \u00e0 tout moment votre taux et vos acomptes de pr\u00e9l\u00e8vement \u00e0 la source. Sans oublier de d\u00e9caler vos paiements d\u2019un mois sur l\u2019autre (jusqu\u2019\u00e0 trois fois) ou au trimestre suivant.<\/li>\n<li><strong>Du c\u00f4t\u00e9 de vos cotisations<\/strong>, la derni\u00e8re \u00e9ch\u00e9ance mensuelle n\u2019a pas \u00e9t\u00e9 pr\u00e9lev\u00e9e et vous avez \u00e9galement droit \u00e0 des d\u00e9lais de paiement. Mais attention: toutes les sommes resteront dues \u00e0 terme&#8230;<\/li>\n<\/ul>\n<p>Pour plus de d\u00e9tails sur ces m\u00e9canismes, consultez la <a href=\"https:\/\/minefi.hosting.augure.com\/Augure_Minefi\/r\/ContenuEnLigne\/Download?id=94121415-41E5-42B7-889D-2250B9E47E52&amp;filename=2077%20-%20Brochure%20fiches%20pratiques%20sur%20les%20mesures%20de%20soutien.pdf\">note explicative publi\u00e9e par le Gouvernement<\/a>.<\/p>\n<ol start=\"2\">\n<li><strong>\u00c7a ne suffit pas? <\/strong><\/li>\n<\/ol>\n<ul>\n<li><strong>Imp\u00f4ts directs<\/strong>: si un plan d\u2019\u00e9chelonnement de vos obligations fiscales n\u2019est pas suffisant, vous pouvez introduire une demande de remise de vos imp\u00f4ts directs (imp\u00f4t sur les b\u00e9n\u00e9fices, contribution \u00e9conomique territoriale, etc.). Ce n\u2019est pas automatique et votre demande fera l\u2019objet d\u2019une analyse d\u00e9taill\u00e9e\u2026<\/li>\n<li><strong>Charges mensuelles<\/strong>: vos difficult\u00e9s s\u2019accentuent? Mettez aussi en suspens certaines d\u00e9penses r\u00e9currentes: loyers, factures d\u2019eau, de gaz ou d\u2019\u00e9lectricit\u00e9. Pour ce faire, vous devez envoyer un mail ou appeler votre fournisseur afin de lui proposer le report \u00e0 l\u2019amiable de vos factures. Ce n\u2019est pas gagn\u00e9 d\u2019office, mais qui ne tente rien n\u2019a rien.<\/li>\n<\/ul>\n<ol start=\"3\">\n<li><strong>Gardez un \u0153il sur la TVA\u2026 <\/strong><\/li>\n<\/ol>\n<p>M\u00eame si aucun report n\u2019est (pour l\u2019instant) pr\u00e9vu du c\u00f4t\u00e9 de la TVA, vous avez toujours la possibilit\u00e9 d\u2019introduire une demande de d\u00e9lai de paiement en cas de difficult\u00e9s de tr\u00e9sorerie. Cela ne vous dispense pas d\u2019effectuer les d\u00e9clarations comme habituellement. \u00c0 nouveau, c\u2019est une mesure discr\u00e9tionnaire.<\/p>\n<ol start=\"4\">\n<li><strong>Vous avez des employ\u00e9s?<\/strong><\/li>\n<\/ol>\n<p>Pas de report des \u00e9ch\u00e9ances fiscales pour l\u2019imp\u00f4t sur le revenu pr\u00e9lev\u00e9 sur les salaires (pr\u00e9l\u00e8vement \u00e0 la source). Toutefois, comme pour la TVA, prenez contact avec votre SIE pour essayer de retarder vos paiements. Votre demande devrait \u00eatre trait\u00e9e avec \u00ab\u00a0bienveillance\u00a0\u00bb compte tenu du contexte actuel\u2026<\/p>\n<p>Autre mesure pour votre personnel? Si vous devez r\u00e9duire la voilure ou \u00eates \u00e0 l\u2019arr\u00eat, vous avez la possibilit\u00e9 <a href=\"https:\/\/activitepartielle.emploi.gouv.fr\/aparts\/\">de mettre vos salari\u00e9s au ch\u00f4mage partiel<\/a>. Vous \u00ab\u00a0ne payez plus que\u00a0\u00bb 70% de leur salaire brut, soit 84% du salaire net, et vous serez int\u00e9gralement rembours\u00e9 par l\u2019\u00c9tat jusqu\u2019au plafond de 6\u2009927\u00a0euros bruts mensuels par salari\u00e9. Un dispositif qui touche d\u00e9j\u00e0 plus 700\u2009000\u00a0salari\u00e9s dans l\u2019Hexagone.<\/p>\n<h3><strong>Financement: \u00e0 quel<\/strong><strong>le porte frapper?<\/strong><\/h3>\n<ol>\n<li><strong>Sollicitez un pr\u00eat \u00e0 votre banque<\/strong><\/li>\n<\/ol>\n<p>300\u00a0milliards d\u2019euros: c\u2019est le montant des garanties accord\u00e9es par l\u2019\u00c9tat aux banques. Le but? Faciliter l\u2019octroi de cr\u00e9dits de tr\u00e9sorerie pour assurer la poursuite des activit\u00e9s et pr\u00e9server au maximum l\u2019emploi. Prenez donc contact avec votre banquier plus rapidement possible pour introduire une demande de financement\u2026<\/p>\n<p>De plus, les banques fran\u00e7aises se sont engag\u00e9es \u00e0 reporter \u2014 jusqu\u2019\u00e0 6\u00a0mois et sans frais \u2014 le remboursement des cr\u00e9dits. D\u2019autres sursis exceptionnels sont \u00e9galement possibles, mais votre demande fera l\u2019objet d\u2019un examen de la part de votre banquier.<\/p>\n<p>Sans oublier, les mesures prises par la Banque publique d\u2019investissement (BPI) pour:<\/p>\n<ul>\n<li>Proposer des pr\u00eats avec un diff\u00e9r\u00e9 de remboursement du capital;<\/li>\n<li>Suspendre le paiement des \u00e9ch\u00e9ances de pr\u00eats accord\u00e9s;<\/li>\n<li>Accorder aux entreprises une \u00e9ch\u00e9ance plus longue pour le paiement de leurs factures, assorti d\u2019un cr\u00e9dit de tr\u00e9sorerie repr\u00e9sentant 30% des volumes mobilis\u00e9s;<\/li>\n<li>Et assurer une garantie \u00e0 hauteur de 90% des cr\u00e9dits bancaires.<\/li>\n<\/ul>\n<ol start=\"2\">\n<li><strong>Une aide \u00ab\u00a0conditionn\u00e9e\u00a0\u00bb de 1500\u00a0euros<\/strong><\/li>\n<\/ol>\n<p>Vous avez \u00e9t\u00e9 forc\u00e9 de fermer vos portes? Votre chiffre d\u2019affaires a recul\u00e9 d\u2019au moins 70% par rapport \u00e0 mars 2019? \u00c0 partir de la fin du mois de mars, vous pourrez toucher un soutien automatique (sur d\u00e9claration) de 1\u2009500\u00a0euros. Des fonds compl\u00e9mentaires pourront \u00eatre d\u00e9gag\u00e9s pour \u00e9viter la faillite, mais ce sera, une nouvelle fois, au cas par cas.<\/p>\n<h3><strong>Cherchez vos propres solutions!<\/strong><\/h3>\n<p>Cet arsenal de mesures est plus que n\u00e9cessaire, mais de nombreuses incertitudes continuent de planer. Combien de temps faudra-t-il pour b\u00e9n\u00e9ficier concr\u00e8tement de ces aides? Ces m\u00e9canismes seront-ils \u00e9tendus si la crise se prolonge? Aurez-vous acc\u00e8s aux m\u00e9canismes discr\u00e9tionnaires? Cela revient \u00e0 introduire un dossier et attendre\u2026 en esp\u00e9rant r\u00e9pondre aux crit\u00e8res impos\u00e9s. Du c\u00f4t\u00e9 des banques, pourront-elles r\u00e9pondre \u00ab\u00a0seules\u00a0\u00bb aux demandes de cr\u00e9dit en cascade? Rien n\u2019est moins s\u00fbr. L\u2019attente risque d\u2019\u00eatre longue et p\u00e9nible, alors tournez-vous, en parall\u00e8le, vers d\u2019autres <a href=\"https:\/\/edebex.com\/blog\/FR-fr\/financement-FR-fr\/10-sources-de-financement-pour-votre-entreprise\">sources de financement<\/a>.<\/p>\n<h3><strong>\u00c9vitez l\u2019effet boule de neige des impay\u00e9s<\/strong><\/h3>\n<p>Vous le savez: les retards de paiement risquent d\u2019exploser au cours des prochains mois\u2026 Toutes les entreprises vont avoir tendance \u00e0 freiner leurs r\u00e8glements, par prudence ou face \u00e0 des difficult\u00e9s incompressibles. Que faire dans ce contexte pour r\u00e9cup\u00e9rer votre d\u00fb? L\u2019affacturage est une option, mais la formule s\u2019av\u00e8re <a href=\"https:\/\/edebex.com\/fr\/blog\/pourquoi-laffacturage-nest-il-pas-forcement-fait-pour-votre-pme\/\">souvent trop complexe et peu r\u00e9active<\/a>. C\u2019est tout le contraire dont vous avez besoin. Si vous n\u2019y avez pas encore song\u00e9, pourquoi ne pas vendre vos factures en ligne? Une solution qui vous assure un <a href=\"https:\/\/edebex.com\/blog\/FR-fr\/financement-FR-fr\/vendre-ses-factures-les-avantages-de-laffacturage-la-liberte-en-plus\">acc\u00e8s rapide \u00e0 des liquidit\u00e9s<\/a>, de forme simple, s\u00e9curis\u00e9e et sans engagement. Ne laissez pas tra\u00eener vos factures!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La plan\u00e8te est l\u2019arr\u00eat. Cette crise sanitaire sans pr\u00e9c\u00e9dent r\u00e9cent fragilise l\u2019ensemble de l\u2019\u00e9difice \u00e9conomique, \u00e0 commencer par les PME. L\u2019heure est grave et il faut agir vite\u2026 et bien! Premiers pas? Sautez sur les mesures d\u2019urgence mises en place par le Gouvernement. Que votre activit\u00e9 soit paralys\u00e9e, en demi-teinte ou qu\u2019elle tourne au contraire [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":3808,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[167],"tags":[],"class_list":["post-3806","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-financial-management"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Coronavirus: comment &quot;sauver&quot; votre tr\u00e9sorerie? | Edebex<\/title>\n<meta name=\"description\" content=\"La crise du coronavirus risque de faire exploser les retards de paiement! N\u2019attendez pas: vendez vos factures en ligne et r\u00e9cup\u00e9rez vos liquidit\u00e9s.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/edebex.com\/fr\/blog\/coronavirus-comment-sauver-votre-tresorerie\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coronavirus: comment &quot;sauver&quot; votre tr\u00e9sorerie?\" \/>\n<meta property=\"og:description\" content=\"La crise du coronavirus risque de faire exploser les retards de paiement! N\u2019attendez pas: vendez vos factures en ligne et r\u00e9cup\u00e9rez vos liquidit\u00e9s.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/edebex.com\/fr\/blog\/coronavirus-comment-sauver-votre-tresorerie\/\" \/>\n<meta property=\"og:site_name\" content=\"edebex\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Edebex\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-16T15:50:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-11T14:07:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/edebex.com\/wp-content\/uploads\/2020\/04\/pic-blog-article-corona.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"2000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"marketing intern 2\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@edebex\" \/>\n<meta name=\"twitter:site\" content=\"@edebex\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"marketing intern 2\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/edebex.com\\\/fr\\\/blog\\\/coronavirus-comment-sauver-votre-tresorerie\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/edebex.com\\\/fr\\\/blog\\\/coronavirus-comment-sauver-votre-tresorerie\\\/\"},\"author\":{\"name\":\"marketing intern 2\",\"@id\":\"https:\\\/\\\/edebex.com\\\/fr\\\/#\\\/schema\\\/person\\\/2e6c66bcddfee6fad192582a126dd021\"},\"headline\":\"Coronavirus: comment \u00ab\u00a0sauver\u00a0\u00bb votre tr\u00e9sorerie?\",\"datePublished\":\"2020-04-16T15:50:18+00:00\",\"dateModified\":\"2021-02-11T14:07:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/edebex.com\\\/fr\\\/blog\\\/coronavirus-comment-sauver-votre-tresorerie\\\/\"},\"wordCount\":1297,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/edebex.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/edebex.com\\\/fr\\\/blog\\\/coronavirus-comment-sauver-votre-tresorerie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/edebex.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/pic-blog-article-corona.jpg\",\"articleSection\":[\"Financial management\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/edebex.com\\\/fr\\\/blog\\\/coronavirus-comment-sauver-votre-tresorerie\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/edebex.com\\\/fr\\\/blog\\\/coronavirus-comment-sauver-votre-tresorerie\\\/\",\"url\":\"https:\\\/\\\/edebex.com\\\/fr\\\/blog\\\/coronavirus-comment-sauver-votre-tresorerie\\\/\",\"name\":\"Coronavirus: comment \\\"sauver\\\" votre tr\u00e9sorerie? | Edebex\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/edebex.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/edebex.com\\\/fr\\\/blog\\\/coronavirus-comment-sauver-votre-tresorerie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/edebex.com\\\/fr\\\/blog\\\/coronavirus-comment-sauver-votre-tresorerie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/edebex.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/pic-blog-article-corona.jpg\",\"datePublished\":\"2020-04-16T15:50:18+00:00\",\"dateModified\":\"2021-02-11T14:07:46+00:00\",\"description\":\"La crise du coronavirus risque de faire exploser les retards de paiement! N\u2019attendez pas: vendez vos factures en ligne et r\u00e9cup\u00e9rez vos liquidit\u00e9s.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/edebex.com\\\/fr\\\/blog\\\/coronavirus-comment-sauver-votre-tresorerie\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/edebex.com\\\/fr\\\/blog\\\/coronavirus-comment-sauver-votre-tresorerie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/edebex.com\\\/fr\\\/blog\\\/coronavirus-comment-sauver-votre-tresorerie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/edebex.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/pic-blog-article-corona.jpg\",\"contentUrl\":\"https:\\\/\\\/edebex.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/pic-blog-article-corona.jpg\",\"width\":1500,\"height\":2000,\"caption\":\"coronavirus tr\u00e9sorerie\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/edebex.com\\\/fr\\\/blog\\\/coronavirus-comment-sauver-votre-tresorerie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/edebex.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coronavirus: comment \u00ab\u00a0sauver\u00a0\u00bb votre tr\u00e9sorerie?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/edebex.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/edebex.com\\\/fr\\\/\",\"name\":\"edebex - The digital alternative to factoring\",\"description\":\"beta\",\"publisher\":{\"@id\":\"https:\\\/\\\/edebex.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/edebex.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/edebex.com\\\/fr\\\/#organization\",\"name\":\"Edebex\",\"url\":\"https:\\\/\\\/edebex.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/edebex.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/edebex.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/logo-edebex.png\",\"contentUrl\":\"https:\\\/\\\/edebex.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/logo-edebex.png\",\"width\":464,\"height\":216,\"caption\":\"Edebex\"},\"image\":{\"@id\":\"https:\\\/\\\/edebex.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Edebex\",\"https:\\\/\\\/x.com\\\/edebex\",\"https:\\\/\\\/www.instagram.com\\\/edebex_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/edebex\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7KdkFY6t-CJvz5l6tTFAlw\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/edebex.com\\\/fr\\\/#\\\/schema\\\/person\\\/2e6c66bcddfee6fad192582a126dd021\",\"name\":\"marketing intern 2\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ac478fcdbb2c06218c09daa92158a75ad2e51ff29f99cf22643fc781fe7c62c8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ac478fcdbb2c06218c09daa92158a75ad2e51ff29f99cf22643fc781fe7c62c8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ac478fcdbb2c06218c09daa92158a75ad2e51ff29f99cf22643fc781fe7c62c8?s=96&d=mm&r=g\",\"caption\":\"marketing intern 2\"},\"url\":\"https:\\\/\\\/edebex.com\\\/fr\\\/blog\\\/author\\\/marketing-intern-2\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Coronavirus: comment \"sauver\" votre tr\u00e9sorerie? | Edebex","description":"La crise du coronavirus risque de faire exploser les retards de paiement! N\u2019attendez pas: vendez vos factures en ligne et r\u00e9cup\u00e9rez vos liquidit\u00e9s.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/edebex.com\/fr\/blog\/coronavirus-comment-sauver-votre-tresorerie\/","og_locale":"fr_FR","og_type":"article","og_title":"Coronavirus: comment \"sauver\" votre tr\u00e9sorerie?","og_description":"La crise du coronavirus risque de faire exploser les retards de paiement! N\u2019attendez pas: vendez vos factures en ligne et r\u00e9cup\u00e9rez vos liquidit\u00e9s.","og_url":"https:\/\/edebex.com\/fr\/blog\/coronavirus-comment-sauver-votre-tresorerie\/","og_site_name":"edebex","article_publisher":"https:\/\/www.facebook.com\/Edebex","article_published_time":"2020-04-16T15:50:18+00:00","article_modified_time":"2021-02-11T14:07:46+00:00","og_image":[{"width":1500,"height":2000,"url":"https:\/\/edebex.com\/wp-content\/uploads\/2020\/04\/pic-blog-article-corona.jpg","type":"image\/jpeg"}],"author":"marketing intern 2","twitter_card":"summary_large_image","twitter_creator":"@edebex","twitter_site":"@edebex","twitter_misc":{"\u00c9crit par":"marketing intern 2","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/edebex.com\/fr\/blog\/coronavirus-comment-sauver-votre-tresorerie\/#article","isPartOf":{"@id":"https:\/\/edebex.com\/fr\/blog\/coronavirus-comment-sauver-votre-tresorerie\/"},"author":{"name":"marketing intern 2","@id":"https:\/\/edebex.com\/fr\/#\/schema\/person\/2e6c66bcddfee6fad192582a126dd021"},"headline":"Coronavirus: comment \u00ab\u00a0sauver\u00a0\u00bb votre tr\u00e9sorerie?","datePublished":"2020-04-16T15:50:18+00:00","dateModified":"2021-02-11T14:07:46+00:00","mainEntityOfPage":{"@id":"https:\/\/edebex.com\/fr\/blog\/coronavirus-comment-sauver-votre-tresorerie\/"},"wordCount":1297,"commentCount":0,"publisher":{"@id":"https:\/\/edebex.com\/fr\/#organization"},"image":{"@id":"https:\/\/edebex.com\/fr\/blog\/coronavirus-comment-sauver-votre-tresorerie\/#primaryimage"},"thumbnailUrl":"https:\/\/edebex.com\/wp-content\/uploads\/2020\/04\/pic-blog-article-corona.jpg","articleSection":["Financial management"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/edebex.com\/fr\/blog\/coronavirus-comment-sauver-votre-tresorerie\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/edebex.com\/fr\/blog\/coronavirus-comment-sauver-votre-tresorerie\/","url":"https:\/\/edebex.com\/fr\/blog\/coronavirus-comment-sauver-votre-tresorerie\/","name":"Coronavirus: comment \"sauver\" votre tr\u00e9sorerie? | Edebex","isPartOf":{"@id":"https:\/\/edebex.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/edebex.com\/fr\/blog\/coronavirus-comment-sauver-votre-tresorerie\/#primaryimage"},"image":{"@id":"https:\/\/edebex.com\/fr\/blog\/coronavirus-comment-sauver-votre-tresorerie\/#primaryimage"},"thumbnailUrl":"https:\/\/edebex.com\/wp-content\/uploads\/2020\/04\/pic-blog-article-corona.jpg","datePublished":"2020-04-16T15:50:18+00:00","dateModified":"2021-02-11T14:07:46+00:00","description":"La crise du coronavirus risque de faire exploser les retards de paiement! N\u2019attendez pas: vendez vos factures en ligne et r\u00e9cup\u00e9rez vos liquidit\u00e9s.","breadcrumb":{"@id":"https:\/\/edebex.com\/fr\/blog\/coronavirus-comment-sauver-votre-tresorerie\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/edebex.com\/fr\/blog\/coronavirus-comment-sauver-votre-tresorerie\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/edebex.com\/fr\/blog\/coronavirus-comment-sauver-votre-tresorerie\/#primaryimage","url":"https:\/\/edebex.com\/wp-content\/uploads\/2020\/04\/pic-blog-article-corona.jpg","contentUrl":"https:\/\/edebex.com\/wp-content\/uploads\/2020\/04\/pic-blog-article-corona.jpg","width":1500,"height":2000,"caption":"coronavirus tr\u00e9sorerie"},{"@type":"BreadcrumbList","@id":"https:\/\/edebex.com\/fr\/blog\/coronavirus-comment-sauver-votre-tresorerie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/edebex.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Coronavirus: comment \u00ab\u00a0sauver\u00a0\u00bb votre tr\u00e9sorerie?"}]},{"@type":"WebSite","@id":"https:\/\/edebex.com\/fr\/#website","url":"https:\/\/edebex.com\/fr\/","name":"edebex - The digital alternative to factoring","description":"beta","publisher":{"@id":"https:\/\/edebex.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/edebex.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/edebex.com\/fr\/#organization","name":"Edebex","url":"https:\/\/edebex.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/edebex.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/edebex.com\/wp-content\/uploads\/2019\/12\/logo-edebex.png","contentUrl":"https:\/\/edebex.com\/wp-content\/uploads\/2019\/12\/logo-edebex.png","width":464,"height":216,"caption":"Edebex"},"image":{"@id":"https:\/\/edebex.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Edebex","https:\/\/x.com\/edebex","https:\/\/www.instagram.com\/edebex_off\/","https:\/\/www.linkedin.com\/company\/edebex\/","https:\/\/www.youtube.com\/channel\/UC7KdkFY6t-CJvz5l6tTFAlw"]},{"@type":"Person","@id":"https:\/\/edebex.com\/fr\/#\/schema\/person\/2e6c66bcddfee6fad192582a126dd021","name":"marketing intern 2","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/ac478fcdbb2c06218c09daa92158a75ad2e51ff29f99cf22643fc781fe7c62c8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ac478fcdbb2c06218c09daa92158a75ad2e51ff29f99cf22643fc781fe7c62c8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ac478fcdbb2c06218c09daa92158a75ad2e51ff29f99cf22643fc781fe7c62c8?s=96&d=mm&r=g","caption":"marketing intern 2"},"url":"https:\/\/edebex.com\/fr\/blog\/author\/marketing-intern-2\/"}]}},"_links":{"self":[{"href":"https:\/\/edebex.com\/fr\/wp-json\/wp\/v2\/posts\/3806","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/edebex.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/edebex.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/edebex.com\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/edebex.com\/fr\/wp-json\/wp\/v2\/comments?post=3806"}],"version-history":[{"count":3,"href":"https:\/\/edebex.com\/fr\/wp-json\/wp\/v2\/posts\/3806\/revisions"}],"predecessor-version":[{"id":6376,"href":"https:\/\/edebex.com\/fr\/wp-json\/wp\/v2\/posts\/3806\/revisions\/6376"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/edebex.com\/fr\/wp-json\/wp\/v2\/media\/3808"}],"wp:attachment":[{"href":"https:\/\/edebex.com\/fr\/wp-json\/wp\/v2\/media?parent=3806"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/edebex.com\/fr\/wp-json\/wp\/v2\/categories?post=3806"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/edebex.com\/fr\/wp-json\/wp\/v2\/tags?post=3806"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}