{"id":7401,"date":"2021-07-28T10:55:45","date_gmt":"2021-07-28T09:55:45","guid":{"rendered":"https:\/\/edebex.com\/?p=7401"},"modified":"2021-07-28T15:29:34","modified_gmt":"2021-07-28T14:29:34","slug":"comment-plaire-a-votre-banquier","status":"publish","type":"post","link":"https:\/\/edebex.com\/fr\/blog\/comment-plaire-a-votre-banquier\/","title":{"rendered":"Comment plaire \u00e0 votre banquier ?"},"content":{"rendered":"\n<h5 class=\"wp-block-heading\" id=\"h-que-ce-soit-pour-une-autorisation-de-d-couvert-le-r-chelonnement-d-un-cr-dit-ou-un-nouveau-financement-rencontrer-votre-banquier-est-rarement-une-partie-de-plaisir-il-faut-sans-cesse-convaincre-cet-interlocuteur-privil-gi-de-votre-entreprise-voici-quelques-conseils\"><strong>Que ce soit pour une autorisation de d\u00e9couvert, le r\u00e9\u00e9chelonnement d&rsquo;un cr\u00e9dit ou un nouveau financement, rencontrer votre banquier est rarement une partie de plaisir. Il faut sans cesse convaincre cet interlocuteur privil\u00e9gi\u00e9 de votre entreprise\u2026 Voici quelques conseils.<\/strong><\/h5>\n\n\n\n<p>Dans le contexte actuel, vous avez tout int\u00e9r\u00eat \u00e0 prendre contact avec votre banque, \u00e0 la fois pour reporter certaines \u00e9ch\u00e9ances de cr\u00e9dit ou solliciter un nouveau pr\u00eat. Vous angoissez \u00e0 l&rsquo;avance? De tout temps et quelle que soit la raison de la visite, votre entreprise est forc\u00e9ment pass\u00e9e au crible. Le banquier \u00e9value votre situation financi\u00e8re et le contexte global de votre PME. La cl\u00e9 pour r\u00e9ussir votre rendez-vous? Pr\u00e9parez-vous<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-1-vitez-de-le-mettre-dos-au-mur\"><strong>1. \u00c9vitez de le mettre dos au mur<\/strong><\/h3>\n\n\n\n<p>En g\u00e9n\u00e9ral, un banquier n\u2019aime pas les situations d&rsquo;urgence. M\u00eame si la crise du coronavirus est soudaine, n&rsquo;attendez pas que le contexte s&rsquo;aggrave davantage pour le contacter. Agissez rapidement afin de ne pas le placer devant le fait accompli. Il appr\u00e9ciera votre capacit\u00e9 \u00e0 \u00ab\u00a0anticiper\u00a0\u00bb les difficult\u00e9s\u2026<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-2-offrez-lui-une-image-fid-le-de-votre-entreprise\">2. <strong>Offrez-lui une image fid\u00e8le de votre entreprise<\/strong><\/h3>\n\n\n\n<p>Si vous souhaitez voir votre demande aboutir, cr\u00e9ez les conditions n\u00e9cessaires pour que votre banquier vous comprenne. C&rsquo;est un partenaire cl\u00e9, alors cultivez la transparence. Pr\u00e9parez un dossier complet et structur\u00e9 reprenant votre situation financi\u00e8re, vos besoins, votre strat\u00e9gie, etc. Autrement dit: une vision coh\u00e9rente et r\u00e9aliste de votre entreprise. Veillez \u00e0 ce que les donn\u00e9es soient fiables et facilement compr\u00e9hensibles.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-3-pr-sentez-des-l-ments-concrets\">3. <strong>Pr\u00e9sentez des \u00e9l\u00e9ments concrets<\/strong><\/h3>\n\n\n\n<p>Ne vous contentez de belles paroles, votre banquier est avant tout <a href=\"https:\/\/edebex.com\/fr-be\/blog\/parlez-vous-le-banquier-sept-definitions-pour-vous-sauver-la-vie\/\">un professionnel du chiffre<\/a>. Outils de suivi, plan de tr\u00e9sorerie, budget pr\u00e9visionnel, plan de financement, compte de r\u00e9sultat, calculs de ratios (de rentabilit\u00e9) ou bilan, autant de documents essentiels pour justifier votre demande. Une mani\u00e8re d&rsquo;attester la faisabilit\u00e9 du \u00ab\u00a0projet\u00a0\u00bb ou la solidit\u00e9 de votre PME, de d\u00e9montrer votre capacit\u00e9 \u00e0 diriger votre entreprise et de rester en bonne position dans la n\u00e9gociation\u2026 La banque vous \u00e9valuera sur cette base, alors pensez aussi \u00e0 soigner votre \u00ab\u00a0administratif\u00a0\u00bb (respect de vos obligations comptables, fiscales et sociales, retards de paiement, etc.).<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-4-soyez-pr-t-discuter-garanties\">4. <strong>Soyez pr\u00eat \u00e0 discuter \u00ab\u00a0garanties\u00a0\u00bb<\/strong><\/h3>\n\n\n\n<p>G\u00e9rer le risque est la pr\u00e9occupation principale d\u2019une banque: celui de vous pr\u00eater de l&rsquo;argent ou de vous accorder des facilit\u00e9s de paiement. Voil\u00e0 pourquoi vous devez g\u00e9n\u00e9ralement offrir des garanties (cautionnement, nantissement sur actifs financiers, hypoth\u00e8que), en fonction du risque pris par l&rsquo;institution. Vu le contexte actuel, <a href=\"https:\/\/www.economie.gouv.fr\/covid19-soutien-entreprises\" target=\"_blank\" rel=\"noreferrer noopener\">le Gouvernement a pris des mesures pour soutenir les entreprises<\/a> en concluant un accord avec le secteur financier, renseignez-vous sur celles applicables \u00e0 votre situation.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-5-optimisez-vos-liquidit-s\">5. <strong>Optimisez vos liquidit\u00e9s<\/strong><\/h3>\n\n\n\n<p>Vous le savez: la gestion de tr\u00e9sorerie est un \u00e9l\u00e9ment capital de la sant\u00e9 financi\u00e8re de votre entreprise. Et encore plus en p\u00e9riode de difficult\u00e9s. Votre banquier se penchera forc\u00e9ment dessus. Il mettra en parall\u00e8le les d\u00e9lais de paiement accord\u00e9s \u00e0 vos clients et ceux de vos fournisseurs. Il pourrait tiquer devant le volume de vos impay\u00e9s ou <a href=\"https:\/\/edebex.com\/fr\/blog\/8-conseils-pour-mieux-evaluer-la-solvabilite-de-vos-prospects\/\" target=\"_blank\" rel=\"noreferrer noopener\">la solidit\u00e9 de vos principaux clients<\/a>. Autant de raisons pour rendre votre gestion de tr\u00e9sorerie irr\u00e9prochable et pr\u00e9server au maximum vos liquidit\u00e9s\u2026<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-6-prenez-soin-de-votre-relation\">6. <strong>Prenez soin de votre relation<\/strong><\/h3>\n\n\n\n<p>La confiance se construit dans la dur\u00e9e. Apr\u00e8s avoir fait bonne impression, poursuivez sur votre lanc\u00e9e car vous serez amen\u00e9 \u00e0 revoir votre interlocuteur. Informez-le de tout changement important. M\u00eame si tout roule, tenez-le r\u00e9guli\u00e8rement (une fois par an au moins) au courant de l&rsquo;\u00e9volution de la situation. Une fa\u00e7on de continuer \u00e0 prouver la qualit\u00e9 de votre gestion et la cr\u00e9dibilit\u00e9 de votre entreprise (et donc sa \u00ab\u00a0notation\u00a0\u00bb) aux yeux de la banque.<\/p>\n\n\n\n<p><br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Que ce soit pour une autorisation de d\u00e9couvert, le r\u00e9\u00e9chelonnement d&rsquo;un cr\u00e9dit ou un nouveau financement, rencontrer votre banquier est rarement une partie de plaisir. Il faut sans cesse convaincre cet interlocuteur privil\u00e9gi\u00e9 de votre entreprise\u2026 Voici quelques conseils!<\/p>\n","protected":false},"author":11,"featured_media":7404,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[436],"tags":[],"class_list":["post-7401","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gestion-entreprise"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Comment plaire \u00e0 votre banquier ? &#8211; edebex<\/title>\n<meta name=\"description\" content=\"Rencontrer votre banquier est rarement une partie de plaisir. Voici quelques conseils pour convaincre cet interlocuteur incontournable.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/edebex.com\/fr\/blog\/comment-plaire-a-votre-banquier\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comment plaire \u00e0 votre banquier ?\" \/>\n<meta property=\"og:description\" content=\"Rencontrer votre banquier est rarement une partie de plaisir. Voici quelques conseils pour convaincre cet interlocuteur incontournable.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/edebex.com\/fr\/blog\/comment-plaire-a-votre-banquier\/\" \/>\n<meta property=\"og:site_name\" content=\"edebex\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Edebex\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-28T09:55:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-28T14:29:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/edebex.com\/wp-content\/uploads\/2021\/07\/Design-sans-titre-9.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1350\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"charlotte escoffier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@edebex\" \/>\n<meta name=\"twitter:site\" content=\"@edebex\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"charlotte escoffier\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/edebex.com\\\/fr\\\/blog\\\/comment-plaire-a-votre-banquier\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/edebex.com\\\/fr\\\/blog\\\/comment-plaire-a-votre-banquier\\\/\"},\"author\":{\"name\":\"charlotte escoffier\",\"@id\":\"https:\\\/\\\/edebex.com\\\/fr\\\/#\\\/schema\\\/person\\\/be69c9c8866a4ee388e585553353822f\"},\"headline\":\"Comment plaire \u00e0 votre banquier ?\",\"datePublished\":\"2021-07-28T09:55:45+00:00\",\"dateModified\":\"2021-07-28T14:29:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/edebex.com\\\/fr\\\/blog\\\/comment-plaire-a-votre-banquier\\\/\"},\"wordCount\":648,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/edebex.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/edebex.com\\\/fr\\\/blog\\\/comment-plaire-a-votre-banquier\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/edebex.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Design-sans-titre-9.png\",\"articleSection\":[\"Gestion entreprise\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/edebex.com\\\/fr\\\/blog\\\/comment-plaire-a-votre-banquier\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/edebex.com\\\/fr\\\/blog\\\/comment-plaire-a-votre-banquier\\\/\",\"url\":\"https:\\\/\\\/edebex.com\\\/fr\\\/blog\\\/comment-plaire-a-votre-banquier\\\/\",\"name\":\"Comment plaire \u00e0 votre banquier ? &#8211; edebex\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/edebex.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/edebex.com\\\/fr\\\/blog\\\/comment-plaire-a-votre-banquier\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/edebex.com\\\/fr\\\/blog\\\/comment-plaire-a-votre-banquier\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/edebex.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Design-sans-titre-9.png\",\"datePublished\":\"2021-07-28T09:55:45+00:00\",\"dateModified\":\"2021-07-28T14:29:34+00:00\",\"description\":\"Rencontrer votre banquier est rarement une partie de plaisir. Voici quelques conseils pour convaincre cet interlocuteur incontournable.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/edebex.com\\\/fr\\\/blog\\\/comment-plaire-a-votre-banquier\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/edebex.com\\\/fr\\\/blog\\\/comment-plaire-a-votre-banquier\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/edebex.com\\\/fr\\\/blog\\\/comment-plaire-a-votre-banquier\\\/#primaryimage\",\"url\":\"https:\\\/\\\/edebex.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Design-sans-titre-9.png\",\"contentUrl\":\"https:\\\/\\\/edebex.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Design-sans-titre-9.png\",\"width\":1350,\"height\":650},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/edebex.com\\\/fr\\\/blog\\\/comment-plaire-a-votre-banquier\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/edebex.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comment plaire \u00e0 votre banquier ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/edebex.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/edebex.com\\\/fr\\\/\",\"name\":\"edebex - The digital alternative to factoring\",\"description\":\"beta\",\"publisher\":{\"@id\":\"https:\\\/\\\/edebex.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/edebex.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/edebex.com\\\/fr\\\/#organization\",\"name\":\"Edebex\",\"url\":\"https:\\\/\\\/edebex.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/edebex.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/edebex.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/logo-edebex.png\",\"contentUrl\":\"https:\\\/\\\/edebex.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/logo-edebex.png\",\"width\":464,\"height\":216,\"caption\":\"Edebex\"},\"image\":{\"@id\":\"https:\\\/\\\/edebex.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Edebex\",\"https:\\\/\\\/x.com\\\/edebex\",\"https:\\\/\\\/www.instagram.com\\\/edebex_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/edebex\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7KdkFY6t-CJvz5l6tTFAlw\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/edebex.com\\\/fr\\\/#\\\/schema\\\/person\\\/be69c9c8866a4ee388e585553353822f\",\"name\":\"charlotte escoffier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/46d0422c5351971bf695b201786365626994df2f813b35a170d57d6d91010f76?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/46d0422c5351971bf695b201786365626994df2f813b35a170d57d6d91010f76?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/46d0422c5351971bf695b201786365626994df2f813b35a170d57d6d91010f76?s=96&d=mm&r=g\",\"caption\":\"charlotte escoffier\"},\"url\":\"https:\\\/\\\/edebex.com\\\/fr\\\/blog\\\/author\\\/charlotte\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Comment plaire \u00e0 votre banquier ? &#8211; edebex","description":"Rencontrer votre banquier est rarement une partie de plaisir. Voici quelques conseils pour convaincre cet interlocuteur incontournable.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/edebex.com\/fr\/blog\/comment-plaire-a-votre-banquier\/","og_locale":"fr_FR","og_type":"article","og_title":"Comment plaire \u00e0 votre banquier ?","og_description":"Rencontrer votre banquier est rarement une partie de plaisir. Voici quelques conseils pour convaincre cet interlocuteur incontournable.","og_url":"https:\/\/edebex.com\/fr\/blog\/comment-plaire-a-votre-banquier\/","og_site_name":"edebex","article_publisher":"https:\/\/www.facebook.com\/Edebex","article_published_time":"2021-07-28T09:55:45+00:00","article_modified_time":"2021-07-28T14:29:34+00:00","og_image":[{"width":1350,"height":650,"url":"https:\/\/edebex.com\/wp-content\/uploads\/2021\/07\/Design-sans-titre-9.png","type":"image\/png"}],"author":"charlotte escoffier","twitter_card":"summary_large_image","twitter_creator":"@edebex","twitter_site":"@edebex","twitter_misc":{"\u00c9crit par":"charlotte escoffier","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/edebex.com\/fr\/blog\/comment-plaire-a-votre-banquier\/#article","isPartOf":{"@id":"https:\/\/edebex.com\/fr\/blog\/comment-plaire-a-votre-banquier\/"},"author":{"name":"charlotte escoffier","@id":"https:\/\/edebex.com\/fr\/#\/schema\/person\/be69c9c8866a4ee388e585553353822f"},"headline":"Comment plaire \u00e0 votre banquier ?","datePublished":"2021-07-28T09:55:45+00:00","dateModified":"2021-07-28T14:29:34+00:00","mainEntityOfPage":{"@id":"https:\/\/edebex.com\/fr\/blog\/comment-plaire-a-votre-banquier\/"},"wordCount":648,"commentCount":0,"publisher":{"@id":"https:\/\/edebex.com\/fr\/#organization"},"image":{"@id":"https:\/\/edebex.com\/fr\/blog\/comment-plaire-a-votre-banquier\/#primaryimage"},"thumbnailUrl":"https:\/\/edebex.com\/wp-content\/uploads\/2021\/07\/Design-sans-titre-9.png","articleSection":["Gestion entreprise"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/edebex.com\/fr\/blog\/comment-plaire-a-votre-banquier\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/edebex.com\/fr\/blog\/comment-plaire-a-votre-banquier\/","url":"https:\/\/edebex.com\/fr\/blog\/comment-plaire-a-votre-banquier\/","name":"Comment plaire \u00e0 votre banquier ? &#8211; edebex","isPartOf":{"@id":"https:\/\/edebex.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/edebex.com\/fr\/blog\/comment-plaire-a-votre-banquier\/#primaryimage"},"image":{"@id":"https:\/\/edebex.com\/fr\/blog\/comment-plaire-a-votre-banquier\/#primaryimage"},"thumbnailUrl":"https:\/\/edebex.com\/wp-content\/uploads\/2021\/07\/Design-sans-titre-9.png","datePublished":"2021-07-28T09:55:45+00:00","dateModified":"2021-07-28T14:29:34+00:00","description":"Rencontrer votre banquier est rarement une partie de plaisir. Voici quelques conseils pour convaincre cet interlocuteur incontournable.","breadcrumb":{"@id":"https:\/\/edebex.com\/fr\/blog\/comment-plaire-a-votre-banquier\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/edebex.com\/fr\/blog\/comment-plaire-a-votre-banquier\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/edebex.com\/fr\/blog\/comment-plaire-a-votre-banquier\/#primaryimage","url":"https:\/\/edebex.com\/wp-content\/uploads\/2021\/07\/Design-sans-titre-9.png","contentUrl":"https:\/\/edebex.com\/wp-content\/uploads\/2021\/07\/Design-sans-titre-9.png","width":1350,"height":650},{"@type":"BreadcrumbList","@id":"https:\/\/edebex.com\/fr\/blog\/comment-plaire-a-votre-banquier\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/edebex.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Comment plaire \u00e0 votre banquier ?"}]},{"@type":"WebSite","@id":"https:\/\/edebex.com\/fr\/#website","url":"https:\/\/edebex.com\/fr\/","name":"edebex - The digital alternative to factoring","description":"beta","publisher":{"@id":"https:\/\/edebex.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/edebex.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/edebex.com\/fr\/#organization","name":"Edebex","url":"https:\/\/edebex.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/edebex.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/edebex.com\/wp-content\/uploads\/2019\/12\/logo-edebex.png","contentUrl":"https:\/\/edebex.com\/wp-content\/uploads\/2019\/12\/logo-edebex.png","width":464,"height":216,"caption":"Edebex"},"image":{"@id":"https:\/\/edebex.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Edebex","https:\/\/x.com\/edebex","https:\/\/www.instagram.com\/edebex_off\/","https:\/\/www.linkedin.com\/company\/edebex\/","https:\/\/www.youtube.com\/channel\/UC7KdkFY6t-CJvz5l6tTFAlw"]},{"@type":"Person","@id":"https:\/\/edebex.com\/fr\/#\/schema\/person\/be69c9c8866a4ee388e585553353822f","name":"charlotte escoffier","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/46d0422c5351971bf695b201786365626994df2f813b35a170d57d6d91010f76?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/46d0422c5351971bf695b201786365626994df2f813b35a170d57d6d91010f76?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/46d0422c5351971bf695b201786365626994df2f813b35a170d57d6d91010f76?s=96&d=mm&r=g","caption":"charlotte escoffier"},"url":"https:\/\/edebex.com\/fr\/blog\/author\/charlotte\/"}]}},"_links":{"self":[{"href":"https:\/\/edebex.com\/fr\/wp-json\/wp\/v2\/posts\/7401","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/edebex.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/edebex.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/edebex.com\/fr\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/edebex.com\/fr\/wp-json\/wp\/v2\/comments?post=7401"}],"version-history":[{"count":8,"href":"https:\/\/edebex.com\/fr\/wp-json\/wp\/v2\/posts\/7401\/revisions"}],"predecessor-version":[{"id":7419,"href":"https:\/\/edebex.com\/fr\/wp-json\/wp\/v2\/posts\/7401\/revisions\/7419"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/edebex.com\/fr\/wp-json\/wp\/v2\/media\/7404"}],"wp:attachment":[{"href":"https:\/\/edebex.com\/fr\/wp-json\/wp\/v2\/media?parent=7401"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/edebex.com\/fr\/wp-json\/wp\/v2\/categories?post=7401"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/edebex.com\/fr\/wp-json\/wp\/v2\/tags?post=7401"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}